{"id":477,"date":"2017-10-17T10:05:00","date_gmt":"2017-10-17T07:05:00","guid":{"rendered":"https:\/\/bonalive.com\/?p=477"},"modified":"2023-05-04T08:31:14","modified_gmt":"2023-05-04T05:31:14","slug":"new-clinical-articles-of-bonalive-granules","status":"publish","type":"post","link":"https:\/\/www.bonalive.com\/en\/news\/new-clinical-articles-of-bonalive-granules\/","title":{"rendered":"New clinical articles of Bonalive\u00ae granules"},"content":{"rendered":"<p>In our continuous effort to improve science and to supply our worldwide customer network with new clinical data, we have the pleasure to present three new clinical articles where BonAlive\u00ae granules has been used for pediatric aneurysmal bone cysts, mastoid obliteration in non cholesteatomatous chronic otitis media and osteotomy site grafting. All three studies show that BonAlive\u00ae granules is a safe and effective material for use in these indications.<\/p>\n<p><a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/28950789\">Treatment of Aneurysmal Bone Cysts With Bioactive Glass In Children Syv\u00e4nen J et al. Scand J Surg. 2017 Sep 1<\/a><\/p>\n<p><a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/28956143\">Bioactive glass obliteration of the mastoid signi\ufb01cantly improves surgical outcome in non-cholesteatomatous chronic otitis media patients Vos J et al. Eur Arch Otorhinolaryngol. 2017 Sep 27<\/a><\/p>\n<p><a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/28962090\">Osteotomy Site Grafting in Bilateral Sagittal Split Surgery With Bioactive Glass S53P4 for Skeletal Stability Stoor P et al. J Craniofac Surg. 2017 Oct;28(7):1709-1716<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In our continuous effort to improve science and to supply our worldwide customer network with new clinical data, we have the pleasure to present three new clinical articles where BonAlive\u00ae&#8230;<\/p>\n","protected":false},"author":1,"featured_media":861,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[1],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.8 (Yoast SEO v24.4) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>New clinical articles of Bonalive\u00ae granules - Bonalive<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bonalive.com\/en\/news\/new-clinical-articles-of-bonalive-granules\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"New clinical articles of Bonalive\u00ae granules\" \/>\n<meta property=\"og:description\" content=\"In our continuous effort to improve science and to supply our worldwide customer network with new clinical data, we have the pleasure to present three new clinical articles where BonAlive\u00ae...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bonalive.com\/en\/news\/new-clinical-articles-of-bonalive-granules\/\" \/>\n<meta property=\"og:site_name\" content=\"Bonalive\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-17T07:05:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-04T05:31:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bonalive.com\/wp-content\/uploads\/2018\/06\/Bonalive_LinkedIn_Kuvapohja_1200x628px_F_Event_study.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hallinta\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"hallinta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bonalive.com\/en\/news\/new-clinical-articles-of-bonalive-granules\/\",\"url\":\"https:\/\/www.bonalive.com\/en\/news\/new-clinical-articles-of-bonalive-granules\/\",\"name\":\"New clinical articles of Bonalive\u00ae granules - Bonalive\",\"isPartOf\":{\"@id\":\"https:\/\/www.bonalive.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.bonalive.com\/en\/news\/new-clinical-articles-of-bonalive-granules\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.bonalive.com\/en\/news\/new-clinical-articles-of-bonalive-granules\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.bonalive.com\/wp-content\/uploads\/2018\/06\/Bonalive_LinkedIn_Kuvapohja_1200x628px_F_Event_study.jpg\",\"datePublished\":\"2017-10-17T07:05:00+00:00\",\"dateModified\":\"2023-05-04T05:31:14+00:00\",\"author\":{\"@id\":\"https:\/\/www.bonalive.com\/en\/#\/schema\/person\/1ad1fb141a1a819f67d50a6cbdcfc626\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.bonalive.com\/en\/news\/new-clinical-articles-of-bonalive-granules\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bonalive.com\/en\/news\/new-clinical-articles-of-bonalive-granules\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.bonalive.com\/en\/news\/new-clinical-articles-of-bonalive-granules\/#primaryimage\",\"url\":\"https:\/\/www.bonalive.com\/wp-content\/uploads\/2018\/06\/Bonalive_LinkedIn_Kuvapohja_1200x628px_F_Event_study.jpg\",\"contentUrl\":\"https:\/\/www.bonalive.com\/wp-content\/uploads\/2018\/06\/Bonalive_LinkedIn_Kuvapohja_1200x628px_F_Event_study.jpg\",\"width\":1200,\"height\":628,\"caption\":\"Publication\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bonalive.com\/en\/news\/new-clinical-articles-of-bonalive-granules\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.bonalive.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"New clinical articles of Bonalive\u00ae granules\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bonalive.com\/en\/#website\",\"url\":\"https:\/\/www.bonalive.com\/en\/\",\"name\":\"Bonalive\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bonalive.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.bonalive.com\/en\/#\/schema\/person\/1ad1fb141a1a819f67d50a6cbdcfc626\",\"name\":\"hallinta\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.bonalive.com\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c3e3eabd6658cc122b4a14ee02cd09c9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c3e3eabd6658cc122b4a14ee02cd09c9?s=96&d=mm&r=g\",\"caption\":\"hallinta\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"New clinical articles of Bonalive\u00ae granules - Bonalive","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bonalive.com\/en\/news\/new-clinical-articles-of-bonalive-granules\/","og_locale":"en_GB","og_type":"article","og_title":"New clinical articles of Bonalive\u00ae granules","og_description":"In our continuous effort to improve science and to supply our worldwide customer network with new clinical data, we have the pleasure to present three new clinical articles where BonAlive\u00ae...","og_url":"https:\/\/www.bonalive.com\/en\/news\/new-clinical-articles-of-bonalive-granules\/","og_site_name":"Bonalive","article_published_time":"2017-10-17T07:05:00+00:00","article_modified_time":"2023-05-04T05:31:14+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.bonalive.com\/wp-content\/uploads\/2018\/06\/Bonalive_LinkedIn_Kuvapohja_1200x628px_F_Event_study.jpg","type":"image\/jpeg"}],"author":"hallinta","twitter_card":"summary_large_image","twitter_misc":{"Written by":"hallinta","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bonalive.com\/en\/news\/new-clinical-articles-of-bonalive-granules\/","url":"https:\/\/www.bonalive.com\/en\/news\/new-clinical-articles-of-bonalive-granules\/","name":"New clinical articles of Bonalive\u00ae granules - Bonalive","isPartOf":{"@id":"https:\/\/www.bonalive.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bonalive.com\/en\/news\/new-clinical-articles-of-bonalive-granules\/#primaryimage"},"image":{"@id":"https:\/\/www.bonalive.com\/en\/news\/new-clinical-articles-of-bonalive-granules\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bonalive.com\/wp-content\/uploads\/2018\/06\/Bonalive_LinkedIn_Kuvapohja_1200x628px_F_Event_study.jpg","datePublished":"2017-10-17T07:05:00+00:00","dateModified":"2023-05-04T05:31:14+00:00","author":{"@id":"https:\/\/www.bonalive.com\/en\/#\/schema\/person\/1ad1fb141a1a819f67d50a6cbdcfc626"},"breadcrumb":{"@id":"https:\/\/www.bonalive.com\/en\/news\/new-clinical-articles-of-bonalive-granules\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bonalive.com\/en\/news\/new-clinical-articles-of-bonalive-granules\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.bonalive.com\/en\/news\/new-clinical-articles-of-bonalive-granules\/#primaryimage","url":"https:\/\/www.bonalive.com\/wp-content\/uploads\/2018\/06\/Bonalive_LinkedIn_Kuvapohja_1200x628px_F_Event_study.jpg","contentUrl":"https:\/\/www.bonalive.com\/wp-content\/uploads\/2018\/06\/Bonalive_LinkedIn_Kuvapohja_1200x628px_F_Event_study.jpg","width":1200,"height":628,"caption":"Publication"},{"@type":"BreadcrumbList","@id":"https:\/\/www.bonalive.com\/en\/news\/new-clinical-articles-of-bonalive-granules\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bonalive.com\/en\/"},{"@type":"ListItem","position":2,"name":"New clinical articles of Bonalive\u00ae granules"}]},{"@type":"WebSite","@id":"https:\/\/www.bonalive.com\/en\/#website","url":"https:\/\/www.bonalive.com\/en\/","name":"Bonalive","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bonalive.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/www.bonalive.com\/en\/#\/schema\/person\/1ad1fb141a1a819f67d50a6cbdcfc626","name":"hallinta","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.bonalive.com\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c3e3eabd6658cc122b4a14ee02cd09c9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c3e3eabd6658cc122b4a14ee02cd09c9?s=96&d=mm&r=g","caption":"hallinta"}}]}},"_links":{"self":[{"href":"https:\/\/www.bonalive.com\/en\/wp-json\/wp\/v2\/posts\/477"}],"collection":[{"href":"https:\/\/www.bonalive.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bonalive.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bonalive.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bonalive.com\/en\/wp-json\/wp\/v2\/comments?post=477"}],"version-history":[{"count":3,"href":"https:\/\/www.bonalive.com\/en\/wp-json\/wp\/v2\/posts\/477\/revisions"}],"predecessor-version":[{"id":937,"href":"https:\/\/www.bonalive.com\/en\/wp-json\/wp\/v2\/posts\/477\/revisions\/937"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bonalive.com\/en\/wp-json\/wp\/v2\/media\/861"}],"wp:attachment":[{"href":"https:\/\/www.bonalive.com\/en\/wp-json\/wp\/v2\/media?parent=477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bonalive.com\/en\/wp-json\/wp\/v2\/categories?post=477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bonalive.com\/en\/wp-json\/wp\/v2\/tags?post=477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}